{"id":6392,"date":"2020-04-06T13:15:22","date_gmt":"2020-04-06T13:15:22","guid":{"rendered":"https:\/\/www.ahmadiyya-islam.org\/es\/?post_type=faqs&#038;p=6392"},"modified":"2020-04-15T11:57:08","modified_gmt":"2020-04-15T11:57:08","slug":"ramadan-paises-sin-noche","status":"publish","type":"faqs","link":"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/","title":{"rendered":"\u00bfCu\u00e1l es el tiempo para romper el ayuno para aquellos que est\u00e1n en los hemisferios norte y sur, donde el d\u00eda puede durar casi 24 horas?"},"content":{"rendered":"<p>En el tiempo de Santo Profeta Muhammad (sa), los musulmanes no se encontraron con este problema pero el Profeta Muhammad (sa) profetiz\u00f3 sobre el tiempo durante la llegada de Dayyal (el Anticristo) y dijo que uno de sus d\u00edas ser\u00e1n como un a\u00f1o, o un mes, etc. Los compa\u00f1eros preguntaron sobre como hacer las oraciones prescritas si un d\u00eda sera como un a\u00f1o o un mes. El Profeta Muhammad (sa) explic\u00f3 que deben estimar el tiempo de un d\u00eda y hacer las oraciones prescritas seg\u00fan la estimaci\u00f3n.<\/p>\n<p>Era en realidad una profec\u00eda sobre el descubrimiento de partes de la tierra donde pasa eso en el tiempo de Dayyal y Mes\u00edas Prometido.<\/p>\n<p>Este mismo aplica al ayuno, se debe hacer el ayuno haciendo una estimaci\u00f3n. Se puede por ejemplo hacer un ayuno de 12 horas, o usar el horario del pa\u00eds m\u00e1s cercano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ellos tienen que seguir los tiempos en el pa\u00eds m\u00e1s cercano donde haya un ciclo de d\u00eda y noche. <\/p>\n","protected":false},"author":35,"featured_media":6383,"parent":0,"template":"","authors":[],"content_source":[],"class_list":["post-6392","faqs","type-faqs","status-publish","has-post-thumbnail","hentry","topics-ramadan"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.1 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfCu\u00e1l es el tiempo para romper el ayuno para aquellos que est\u00e1n en los hemisferios norte y sur, donde el d\u00eda puede durar casi 24 horas?<\/title>\n<meta name=\"description\" content=\"Ellos tienen que seguir los tiempos en el pa\u00eds m\u00e1s cercano donde haya un ciclo de d\u00eda y noche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1l es el tiempo para romper el ayuno para aquellos que est\u00e1n en los hemisferios norte y sur, donde el d\u00eda puede durar casi 24 horas?\" \/>\n<meta property=\"og:description\" content=\"Ellos tienen que seguir los tiempos en el pa\u00eds m\u00e1s cercano donde haya un ciclo de d\u00eda y noche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/\" \/>\n<meta property=\"og:site_name\" content=\"Comunidad Musulmana Ahmad\u00eda\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-15T11:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ahmadiyya-islam.org\/es\/wp-content\/uploads\/sites\/10\/2020\/04\/shutterstock_236476819-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/preguntas-y-respuestas\\\/ramadan-paises-sin-noche\\\/\",\"url\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/preguntas-y-respuestas\\\/ramadan-paises-sin-noche\\\/\",\"name\":\"\u00bfCu\u00e1l es el tiempo para romper el ayuno para aquellos que est\u00e1n en los hemisferios norte y sur, donde el d\u00eda puede durar casi 24 horas?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/preguntas-y-respuestas\\\/ramadan-paises-sin-noche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/preguntas-y-respuestas\\\/ramadan-paises-sin-noche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2020\\\/04\\\/shutterstock_236476819-1-scaled.jpg\",\"datePublished\":\"2020-04-06T13:15:22+00:00\",\"dateModified\":\"2020-04-15T11:57:08+00:00\",\"description\":\"Ellos tienen que seguir los tiempos en el pa\u00eds m\u00e1s cercano donde haya un ciclo de d\u00eda y noche.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/preguntas-y-respuestas\\\/ramadan-paises-sin-noche\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/preguntas-y-respuestas\\\/ramadan-paises-sin-noche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/preguntas-y-respuestas\\\/ramadan-paises-sin-noche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2020\\\/04\\\/shutterstock_236476819-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2020\\\/04\\\/shutterstock_236476819-1-scaled.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/preguntas-y-respuestas\\\/ramadan-paises-sin-noche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preguntas y respuestas\",\"item\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/preguntas-y-respuestas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfCu\u00e1l es el tiempo para romper el ayuno para aquellos que est\u00e1n en los hemisferios norte y sur, donde el d\u00eda puede durar casi 24 horas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/\",\"name\":\"Comunidad Musulmana Ahmad\u00eda\",\"description\":\"Internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/#organization\",\"name\":\"Comunidad Musulmana Ahmad\u00eda\",\"url\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2015\\\/06\\\/alislam-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2015\\\/06\\\/alislam-logo.png\",\"width\":1859,\"height\":1859,\"caption\":\"Comunidad Musulmana Ahmad\u00eda\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ahmadiyya-islam.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1l es el tiempo para romper el ayuno para aquellos que est\u00e1n en los hemisferios norte y sur, donde el d\u00eda puede durar casi 24 horas?","description":"Ellos tienen que seguir los tiempos en el pa\u00eds m\u00e1s cercano donde haya un ciclo de d\u00eda y noche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1l es el tiempo para romper el ayuno para aquellos que est\u00e1n en los hemisferios norte y sur, donde el d\u00eda puede durar casi 24 horas?","og_description":"Ellos tienen que seguir los tiempos en el pa\u00eds m\u00e1s cercano donde haya un ciclo de d\u00eda y noche.","og_url":"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/","og_site_name":"Comunidad Musulmana Ahmad\u00eda","article_modified_time":"2020-04-15T11:57:08+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-content\/uploads\/sites\/10\/2020\/04\/shutterstock_236476819-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/","url":"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/","name":"\u00bfCu\u00e1l es el tiempo para romper el ayuno para aquellos que est\u00e1n en los hemisferios norte y sur, donde el d\u00eda puede durar casi 24 horas?","isPartOf":{"@id":"https:\/\/www.ahmadiyya-islam.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/#primaryimage"},"image":{"@id":"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-content\/uploads\/sites\/10\/2020\/04\/shutterstock_236476819-1-scaled.jpg","datePublished":"2020-04-06T13:15:22+00:00","dateModified":"2020-04-15T11:57:08+00:00","description":"Ellos tienen que seguir los tiempos en el pa\u00eds m\u00e1s cercano donde haya un ciclo de d\u00eda y noche.","breadcrumb":{"@id":"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/#primaryimage","url":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-content\/uploads\/sites\/10\/2020\/04\/shutterstock_236476819-1-scaled.jpg","contentUrl":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-content\/uploads\/sites\/10\/2020\/04\/shutterstock_236476819-1-scaled.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/ramadan-paises-sin-noche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ahmadiyya-islam.org\/es\/"},{"@type":"ListItem","position":2,"name":"Preguntas y respuestas","item":"https:\/\/www.ahmadiyya-islam.org\/es\/preguntas-y-respuestas\/"},{"@type":"ListItem","position":3,"name":"\u00bfCu\u00e1l es el tiempo para romper el ayuno para aquellos que est\u00e1n en los hemisferios norte y sur, donde el d\u00eda puede durar casi 24 horas?"}]},{"@type":"WebSite","@id":"https:\/\/www.ahmadiyya-islam.org\/es\/#website","url":"https:\/\/www.ahmadiyya-islam.org\/es\/","name":"Comunidad Musulmana Ahmad\u00eda","description":"Internacional","publisher":{"@id":"https:\/\/www.ahmadiyya-islam.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ahmadiyya-islam.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.ahmadiyya-islam.org\/es\/#organization","name":"Comunidad Musulmana Ahmad\u00eda","url":"https:\/\/www.ahmadiyya-islam.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.ahmadiyya-islam.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-content\/uploads\/sites\/10\/2015\/06\/alislam-logo.png","contentUrl":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-content\/uploads\/sites\/10\/2015\/06\/alislam-logo.png","width":1859,"height":1859,"caption":"Comunidad Musulmana Ahmad\u00eda"},"image":{"@id":"https:\/\/www.ahmadiyya-islam.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-json\/wp\/v2\/faqs\/6392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-json\/wp\/v2\/faqs"}],"about":[{"href":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-json\/wp\/v2\/types\/faqs"}],"author":[{"embeddable":true,"href":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-json\/wp\/v2\/users\/35"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-json\/wp\/v2\/media\/6383"}],"wp:attachment":[{"href":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-json\/wp\/v2\/media?parent=6392"}],"wp:term":[{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-json\/wp\/v2\/authors?post=6392"},{"taxonomy":"content_source","embeddable":true,"href":"https:\/\/www.ahmadiyya-islam.org\/es\/wp-json\/wp\/v2\/content_source?post=6392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}